{"id":19472,"date":"2026-05-11T11:22:52","date_gmt":"2026-05-11T11:22:52","guid":{"rendered":"https:\/\/sindilojasfor.org.br\/web\/?p=19472"},"modified":"2026-05-11T11:24:02","modified_gmt":"2026-05-11T11:24:02","slug":"semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo","status":"publish","type":"post","link":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/","title":{"rendered":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo"},"content":{"rendered":"\n<p>O Sistema Fecom\u00e9rcio Cear\u00e1 realiza, nos dias 16 e 17 de maio, a Semana S do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo, proporcionando ao p\u00fablico uma ampla programa\u00e7\u00e3o de cidadania, qualifica\u00e7\u00e3o profissional, cultura e inova\u00e7\u00e3o. Com acesso gratuito mediante inscri\u00e7\u00e3o pr\u00e9via, o evento re\u00fane servi\u00e7os para a popula\u00e7\u00e3o, experi\u00eancias interativas e uma agenda de conte\u00fados voltada ao desenvolvimento dos neg\u00f3cios e das pessoas, tudo alinhado com os benef\u00edcios direcionados diariamente \u00e0 popula\u00e7\u00e3o por meio da Fecom\u00e9rcio, Sesc e Senac.<\/p>\n\n\n\n<p>De acordo com o <strong>presidente em exerc\u00edcio do Sistema Fecom\u00e9rcio Cear\u00e1, Cid Alves<\/strong>, o evento \u00e9 uma oportunidade de apresentar \u00e0 sociedade, de forma pr\u00e1tica, as a\u00e7\u00f5es realizadas pelo Sistema Fecom\u00e9rcio Cear\u00e1 e o impacto desse trabalho na qualidade de vida de milhares de cearenses. \u201cEst\u00e3o todos convidados \u00e0 Semana S, venham conhecer melhor as a\u00e7\u00f5es do Sistema Fecom\u00e9rcio. \u00c9 muito importante para a sociedade do Estado do Cear\u00e1, para as pessoas que querem empreender ou para as que j\u00e1 est\u00e3o na atividade, essa oportunidade de se aprimorar por meio de todas as a\u00e7\u00f5es, os projetos e servi\u00e7os que a Fecom\u00e9rcio, o Sesc e o Senac oferecem\u201d, ressalta.<\/p>\n\n\n\n<p><strong>Conhecimento e inspira\u00e7\u00e3o com grandes nomes<\/strong><\/p>\n\n\n\n<p>Um dos destaques desta edi\u00e7\u00e3o \u00e9 a programa\u00e7\u00e3o de palestras e pain\u00e9is com nomes de refer\u00eancia em inova\u00e7\u00e3o, empreendedorismo e gest\u00e3o. No dia 16 de maio, a agenda come\u00e7a \u00e0s 16h com o consultor&nbsp;<strong>Afonso Alc\u00e2ntara<\/strong>, trazendo reflex\u00f5es sobre a import\u00e2ncia do digital, seguida pelo Painel do Empreendedorismo da Moda e da Beleza, \u00e0s 17h. Na sequ\u00eancia, \u00e0s 18h, o futurista&nbsp;<strong>Gil Giardelli<\/strong>&nbsp;conduz debates sobre gest\u00e3o, lideran\u00e7a&nbsp; e inova\u00e7\u00e3o digital, e, \u00e0s 19h, o medalhista ol\u00edmpico&nbsp;<strong>Lars Grael<\/strong>&nbsp;compartilha experi\u00eancias sobre resili\u00eancia, lideran\u00e7a e transforma\u00e7\u00e3o diante de adversidades.<\/p>\n\n\n\n<p>J\u00e1 no dia 17, a programa\u00e7\u00e3o segue com conte\u00fados voltados a temas estrat\u00e9gicos para o mercado. \u00c0s 18h, o projeto&nbsp;<strong>Pan\u00e3<\/strong>&nbsp;abordar\u00e1 o mapeamento e identifica\u00e7\u00e3o de esp\u00e9cies de insumos alimentares com potencial de cultivo e comercializa\u00e7\u00e3o no Cear\u00e1; e, \u00e0s 19h,&nbsp;<strong>Alexandre Santos<\/strong>&nbsp;encerra a agenda de palestras com discuss\u00f5es sobre Sa\u00fade e Seguran\u00e7a do Trabalho. A programa\u00e7\u00e3o refor\u00e7a a Semana S como um espa\u00e7o de inspira\u00e7\u00e3o, troca de conhecimento e conex\u00e3o com temas que impactam diretamente o com\u00e9rcio, os servi\u00e7os e o turismo.<\/p>\n\n\n\n<p><strong>Qualidade de vida<\/strong><\/p>\n\n\n\n<p>A programa\u00e7\u00e3o tamb\u00e9m refor\u00e7a a atua\u00e7\u00e3o do Sistema Fecom\u00e9rcio em \u00e1reas que dialogam com qualidade de vida, lazer, cultura, sa\u00fade, turismo e educa\u00e7\u00e3o, por meio do Sesc e Senac. O p\u00fablico ter\u00e1 oportunidade de vivenciar diversas experi\u00eancias. A divers\u00e3o est\u00e1 garantida com visita ao planet\u00e1rio, tirolesa, chute a gol, simulador de corrida e exposi\u00e7\u00e3o de brinquedos interativos. Para quem gosta de se cuidar, o espa\u00e7o de bem-estar contar\u00e1 com avalia\u00e7\u00e3o orofacial, fisioterapia, pilates, massagem e balan\u00e7a de bioimped\u00e2ncia. No espa\u00e7o cultura e turismo as pessoas poder\u00e3o se encantar com a beleza da Chapada do Araripe e conhecer os Museus Org\u00e2nicos atrav\u00e9s da experi\u00eancia com \u00f3culos de realidade virtual.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o do&nbsp;<strong>Encontro Sesc Povos do Mar<\/strong>&nbsp;tamb\u00e9m far\u00e1 parte da Semana S com gastronomia, cultura popular, artesanato, oficinas e shows. \u00c9 poss\u00edvel conferir a apresenta\u00e7\u00e3o da culin\u00e1ria dos mestres e mestras do litoral cearense, com degusta\u00e7\u00e3o gratuita;&nbsp; a Casa de Tapioca e a Casa do Peixe Assado; a Feira com 90 artes\u00e3os; oficinas de artesanato; e apresenta\u00e7\u00f5es de tradi\u00e7\u00e3o popular, como maracatu, dan\u00e7a de coco e caretas; al\u00e9m dos shows da&nbsp;<strong>Lagosta Bronzeada<\/strong>, no s\u00e1bado, dia 16, \u00e0s 20h; e para a crian\u00e7ada, o show infantil de&nbsp;<strong>H\u00e9lio Ziskind<\/strong>, no domingo, dia 17, \u00e0s 17h30.<\/p>\n\n\n\n<p>Os eixos de Gastronomia, Gest\u00e3o e Neg\u00f3cios, Sa\u00fade, Seguran\u00e7a do Trabalho, Tecnologia, Beleza e Moda do Senac trazem experi\u00eancias pr\u00e1ticas, rodas de conversa, inova\u00e7\u00e3o aplicada e demonstra\u00e7\u00f5es interativas. Entre os destaques est\u00e3o os projetos integradores da Faculdade Senac, atividades em compet\u00eancias digitais, como o quis interativo sobre trabalho, carreira e gest\u00e3o; \u00e1rea gamer; demonstra\u00e7\u00e3o de tecnologia de drones; atendimentos de maquiagem, penteado e esmalta\u00e7\u00e3o de unhas; atendimento de colora\u00e7\u00e3o pessoal e assessoria de imagem, dentre outros.<\/p>\n\n\n\n<p>A Semana S do Com\u00e9rcio \u00e9 um evento nacional do Sistema Com\u00e9rcio, realizado em todas as capitais, onde empres\u00e1rios, trabalhadores e suas fam\u00edlias conhecem de perto os produtos e servi\u00e7os que impulsionam o setor de bens, servi\u00e7os e turismo.&nbsp;<\/p>\n\n\n\n<p><strong>Servi\u00e7o<\/strong><\/p>\n\n\n\n<p><strong>Semana S do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo<\/strong><\/p>\n\n\n\n<p><strong>Data:&nbsp;<\/strong>16 e&nbsp;17 de maio<\/p>\n\n\n\n<p><strong>Hor\u00e1rio:&nbsp;<\/strong>A partir das 15h<\/p>\n\n\n\n<p><strong>Inscri\u00e7\u00f5es:&nbsp;<\/strong><a href=\"http:\/\/cncsemanasbrasil.facedoor.events\/ce\">cncsemanasbrasil.facedoor.events\/ce<\/a><\/p>\n\n\n\n<p><strong>Programa\u00e7\u00e3o:&nbsp;<\/strong><a href=\"https:\/\/www.fecomercio-ce.com.br\/semana-s\/\">fecomercio-ce.com.br\/semana-s\/<\/a><\/p>\n\n\n\n<p><strong>Local:&nbsp;<\/strong>Aterro da Praia de Iracema \u2013 Av. Historiador Raimundo Gir\u00e3o, 1002<\/p>\n\n\n\n<p>*Gratuito mediante inscri\u00e7\u00e3o<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/www.fecomercio-ce.com.br\/blog\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/\">https:\/\/www.fecomercio-ce.com.br\/blog\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sistema Fecom\u00e9rcio Cear\u00e1 realiza, nos dias 16 e 17 de maio, a Semana S do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo, proporcionando ao p\u00fablico uma ampla programa\u00e7\u00e3o de cidadania, qualifica\u00e7\u00e3o profissional, cultura e inova\u00e7\u00e3o. Com acesso gratuito mediante inscri\u00e7\u00e3o pr\u00e9via, o evento re\u00fane servi\u00e7os para a popula\u00e7\u00e3o, experi\u00eancias interativas e uma agenda de conte\u00fados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza\" \/>\n<meta property=\"og:description\" content=\"O Sistema Fecom\u00e9rcio Cear\u00e1 realiza, nos dias 16 e 17 de maio, a Semana S do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo, proporcionando ao p\u00fablico uma ampla programa\u00e7\u00e3o de cidadania, qualifica\u00e7\u00e3o profissional, cultura e inova\u00e7\u00e3o. Com acesso gratuito mediante inscri\u00e7\u00e3o pr\u00e9via, o evento re\u00fane servi\u00e7os para a popula\u00e7\u00e3o, experi\u00eancias interativas e uma agenda de conte\u00fados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindilojas Fortaleza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SindilojasFortaleza\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T11:22:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:24:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"175\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindilojasFor\" \/>\n<meta name=\"twitter:site\" content=\"@SindilojasFor\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/\"},\"author\":{\"name\":\"Cl\u00e1udio\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#\\\/schema\\\/person\\\/00f29ab2fc2b0bacbe74a1372831e8b7\"},\"headline\":\"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo\",\"datePublished\":\"2026-05-11T11:22:52+00:00\",\"dateModified\":\"2026-05-11T11:24:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/\"},\"wordCount\":889,\"publisher\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semana-S-1.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/\",\"url\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/\",\"name\":\"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semana-S-1.png\",\"datePublished\":\"2026-05-11T11:22:52+00:00\",\"dateModified\":\"2026-05-11T11:24:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semana-S-1.png\",\"contentUrl\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/semana-S-1.png\",\"width\":300,\"height\":175},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/\",\"name\":\"Sindilojas Fortaleza\",\"description\":\"H\u00e1 91 anos, A Casa do Lojista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#organization\",\"name\":\"Sindilojas Fortaleza\",\"url\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo.png\",\"width\":750,\"height\":333,\"caption\":\"Sindilojas Fortaleza\"},\"image\":{\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SindilojasFortaleza\",\"https:\\\/\\\/x.com\\\/SindilojasFor\",\"https:\\\/\\\/www.instagram.com\\\/SindilojasFor\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gerencia-fortaleza-45093a46\\\/\",\"https:\\\/\\\/t.me\\\/sindilojasfortaleza\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQOowPrNcYoeFMK58ZrCxDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindilojasfor.org.br\\\/web\\\/#\\\/schema\\\/person\\\/00f29ab2fc2b0bacbe74a1372831e8b7\",\"name\":\"Cl\u00e1udio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e1udio\"},\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/","og_locale":"pt_BR","og_type":"article","og_title":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza","og_description":"O Sistema Fecom\u00e9rcio Cear\u00e1 realiza, nos dias 16 e 17 de maio, a Semana S do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo, proporcionando ao p\u00fablico uma ampla programa\u00e7\u00e3o de cidadania, qualifica\u00e7\u00e3o profissional, cultura e inova\u00e7\u00e3o. Com acesso gratuito mediante inscri\u00e7\u00e3o pr\u00e9via, o evento re\u00fane servi\u00e7os para a popula\u00e7\u00e3o, experi\u00eancias interativas e uma agenda de conte\u00fados [&hellip;]","og_url":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/","og_site_name":"Sindilojas Fortaleza","article_publisher":"https:\/\/www.facebook.com\/SindilojasFortaleza","article_published_time":"2026-05-11T11:22:52+00:00","article_modified_time":"2026-05-11T11:24:02+00:00","og_image":[{"width":300,"height":175,"url":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png","type":"image\/png"}],"author":"Cl\u00e1udio","twitter_card":"summary_large_image","twitter_creator":"@SindilojasFor","twitter_site":"@SindilojasFor","twitter_misc":{"Escrito por":"Cl\u00e1udio","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#article","isPartOf":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/"},"author":{"name":"Cl\u00e1udio","@id":"https:\/\/sindilojasfor.org.br\/web\/#\/schema\/person\/00f29ab2fc2b0bacbe74a1372831e8b7"},"headline":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo","datePublished":"2026-05-11T11:22:52+00:00","dateModified":"2026-05-11T11:24:02+00:00","mainEntityOfPage":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/"},"wordCount":889,"publisher":{"@id":"https:\/\/sindilojasfor.org.br\/web\/#organization"},"image":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#primaryimage"},"thumbnailUrl":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/","url":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/","name":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo - Sindilojas Fortaleza","isPartOf":{"@id":"https:\/\/sindilojasfor.org.br\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#primaryimage"},"image":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#primaryimage"},"thumbnailUrl":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png","datePublished":"2026-05-11T11:22:52+00:00","dateModified":"2026-05-11T11:24:02+00:00","breadcrumb":{"@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#primaryimage","url":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png","contentUrl":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/04\/semana-S-1.png","width":300,"height":175},{"@type":"BreadcrumbList","@id":"https:\/\/sindilojasfor.org.br\/web\/semana-s-movimenta-fortaleza-com-inovacao-cidadania-e-grandes-nomes-do-empreendedorismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sindilojasfor.org.br\/web\/"},{"@type":"ListItem","position":2,"name":"Semana S movimenta Fortaleza com inova\u00e7\u00e3o, cidadania e grandes nomes do empreendedorismo"}]},{"@type":"WebSite","@id":"https:\/\/sindilojasfor.org.br\/web\/#website","url":"https:\/\/sindilojasfor.org.br\/web\/","name":"Sindilojas Fortaleza","description":"H\u00e1 91 anos, A Casa do Lojista","publisher":{"@id":"https:\/\/sindilojasfor.org.br\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindilojasfor.org.br\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sindilojasfor.org.br\/web\/#organization","name":"Sindilojas Fortaleza","url":"https:\/\/sindilojasfor.org.br\/web\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sindilojasfor.org.br\/web\/#\/schema\/logo\/image\/","url":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/03\/logo.png","contentUrl":"https:\/\/sindilojasfor.org.br\/web\/wp-content\/uploads\/2025\/03\/logo.png","width":750,"height":333,"caption":"Sindilojas Fortaleza"},"image":{"@id":"https:\/\/sindilojasfor.org.br\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SindilojasFortaleza","https:\/\/x.com\/SindilojasFor","https:\/\/www.instagram.com\/SindilojasFor","https:\/\/www.linkedin.com\/in\/gerencia-fortaleza-45093a46\/","https:\/\/t.me\/sindilojasfortaleza","https:\/\/www.youtube.com\/channel\/UCQOowPrNcYoeFMK58ZrCxDQ"]},{"@type":"Person","@id":"https:\/\/sindilojasfor.org.br\/web\/#\/schema\/person\/00f29ab2fc2b0bacbe74a1372831e8b7","name":"Cl\u00e1udio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44e41a55e43cf8b727be88814f56866d09b5842595ebdf3891dc90a43e65c9d0?s=96&d=mm&r=g","caption":"Cl\u00e1udio"},"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/posts\/19472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/comments?post=19472"}],"version-history":[{"count":2,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/posts\/19472\/revisions"}],"predecessor-version":[{"id":19474,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/posts\/19472\/revisions\/19474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/media\/17032"}],"wp:attachment":[{"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/media?parent=19472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/categories?post=19472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindilojasfor.org.br\/web\/wp-json\/wp\/v2\/tags?post=19472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}